{"id":230,"date":"2024-03-07T11:42:24","date_gmt":"2024-03-07T11:42:24","guid":{"rendered":"https:\/\/www.surfers-residence.com\/?page_id=230"},"modified":"2024-04-15T14:30:55","modified_gmt":"2024-04-15T14:30:55","slug":"about-us","status":"publish","type":"page","link":"https:\/\/www.surfers-residence.com\/de\/about-us\/","title":{"rendered":"\u00dcber uns"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"230\" class=\"elementor elementor-230\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5104f7ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5104f7ee\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-38be2d55\" data-id=\"38be2d55\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ad74ecf elementor-widget__width-auto elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7ad74ecf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcber uns<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-159a8d98 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"159a8d98\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3cc88ec0\" data-id=\"3cc88ec0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-16903517 elementor-widget__width-initial elementor-absolute elementor-invisible elementor-widget elementor-widget-image\" data-id=\"16903517\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_animation&quot;:&quot;slideInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2240\" height=\"1493\" src=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Entrada_1.jpg\" class=\"attachment-full size-full wp-image-446\" alt=\"\" srcset=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Entrada_1.jpg 2240w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Entrada_1-300x200.jpg 300w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Entrada_1-1024x683.jpg 1024w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Entrada_1-768x512.jpg 768w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Entrada_1-1536x1024.jpg 1536w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Entrada_1-2048x1365.jpg 2048w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78458bb5 elementor-widget elementor-widget-image\" data-id=\"78458bb5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1440\" height=\"2560\" src=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/SurfersResidence-Roof-Terrace6_1-scaled.jpg\" class=\"attachment-full size-full wp-image-564\" alt=\"\" srcset=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/SurfersResidence-Roof-Terrace6_1-scaled.jpg 1440w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/SurfersResidence-Roof-Terrace6_1-169x300.jpg 169w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/SurfersResidence-Roof-Terrace6_1-576x1024.jpg 576w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/SurfersResidence-Roof-Terrace6_1-768x1366.jpg 768w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/SurfersResidence-Roof-Terrace6_1-864x1536.jpg 864w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/SurfersResidence-Roof-Terrace6_1-1152x2048.jpg 1152w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-590542f0\" data-id=\"590542f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e66e9b9 elementor-widget elementor-widget-heading\" data-id=\"6e66e9b9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Catching the Wind: Der Pionier hinter unserer Passion<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8fb912 elementor-widget elementor-widget-heading\" data-id=\"b8fb912\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Der Geist von Surfers Residence: Juliaan's Verm\u00e4chtnis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3055ac elementor-drop-cap-yes elementor-drop-cap-view-default elementor-widget elementor-widget-text-editor\" data-id=\"b3055ac\" data-element_type=\"widget\" data-settings=\"{&quot;drop_cap&quot;:&quot;yes&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Eine Sportlerin mit einer gro\u00dfen Leidenschaft f\u00fcr das Kitesurfen. Juliaan ist IKO &amp; VDWS Kitelehrer und ein erfolgreicher Gr\u00fcnder. Er hat vor 20 Jahren auf Fuerteventura das Kitesurfen gelernt und ist seither vom Kitevirus infiziert. Um den Sport in seiner ganzen Bandbreite zu erforschen, hat er bereits viele Spots in Europa, Afrika, Asien, Australien, S\u00fcdamerika und der Karibik besucht. Tarifa bietet ihm genau die Bedingungen, nach denen er gesucht hat. Mit der SurfersResidence gibt er seine Wassersportleidenschaft und seine zahlreichen Reisen&#8217; Erfahrungen an seine G\u00e4ste weiter. Jetzt ist das Haus unter neuen Besitzern, mehr Wassersport- und Tarifa-Enthusiasten, aber wir denken, dass diese Geschichte \u00fcber Juliaan wichtig f\u00fcr das Haus und seine Geschichte ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-390331fd elementor-view-stacked elementor-position-left elementor-mobile-position-left elementor-shape-circle elementor-vertical-align-top elementor-widget elementor-widget-icon-box\" data-id=\"390331fd\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon elementor-animation-float\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"ti-world\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSprachen\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEnglisch - Deutsch - Spanisch \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a6e5004 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a6e5004\" data-element_type=\"section\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66be7533\" data-id=\"66be7533\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9b9743b elementor-widget elementor-widget-heading\" data-id=\"9b9743b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wo Wellen von Spa\u00df, Komfort und Pflege verschmelzen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-545cfcbd elementor-widget elementor-widget-heading\" data-id=\"545cfcbd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ihre ultimative K\u00fcstenflucht<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76d7de12 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"76d7de12\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In der Surfers Residence glauben wir daran, ein Erlebnis zu schaffen, das so gro\u00df und vielf\u00e4ltig ist wie der Ozean selbst. Unser Ethos basiert auf drei S\u00e4ulen, die sicherstellen, dass Ihr Aufenthalt aus den richtigen Gr\u00fcnden unvergesslich ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-143ce23f elementor-widget-divider--view-line_icon elementor-widget-divider--separator-type-pattern elementor-view-default elementor-widget-divider--element-align-center elementor-widget elementor-widget-divider\" data-id=\"143ce23f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;none&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 24 24&#039; fill=&#039;none&#039; stroke=&#039;black&#039; stroke-width=&#039;1&#039; stroke-linecap=&#039;square&#039; stroke-miterlimit=&#039;10&#039;%3E%3Cpath d=&#039;M0,6c6,0,0.9,11.1,6.9,11.1S18,6,24,6&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon elementor-divider__element\">\n\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" id=\"Layer_1\" x=\"0px\" y=\"0px\" viewbox=\"0 0 64 64\" style=\"enable-background:new 0 0 64 64;\" xml:space=\"preserve\"><style type=\"text\/css\">\t.st0{fill:none;stroke:#231F20;stroke-width:2;stroke-linecap:round;stroke-linejoin:round;stroke-miterlimit:10;}<\/style><g>\t<path class=\"st0\" d=\"M28.47,24.87l-0.29,3.79c-0.04,0.4,0.07,0.81,0.3,1.13l4.73,7c0.47,0.66,0.34,1.57-0.3,2.07l0,0  c-0.62,0.49-1.51,0.42-2.04-0.16l-6.4-7.03c-1.05-1.13-1.51-2.69-1.22-4.21l1.27-6.77c0.2-1.07,0.84-2.02,1.76-2.61  c1.21-0.78,2.61-1.26,4.06-1.4l0,0c2.92-0.27,5.71,1.31,7.08,3.9c0,0,0.59,1.83,0.8,4.05\"><\/path>\t<path class=\"st0\" d=\"M38.83,41.03c0.45,0.39,0.96,0.74,1.51,1.01l3.54,4.34c0.38,0.53,0.63,0.89,0.93,1.87l3.54,10.29  c0,0.01,0,0.01,0,0.02c-0.14,1.51-2.08,2-3.09,0.88c-0.24-0.26-0.49-0.6-0.72-1.05l-4.71-8.81l-6.32-4.9l-0.02-0.01  c-1.39-0.56-2.85-1.9-3.49-2.64\"><\/path>\t<path class=\"st0\" d=\"M37.9,8.89c0,2.77-2.24,5.01-5.01,5.01s-5.01-2.24-5.01-5.01c0-2.77,2.24-5.01,5.01-5.01S37.9,6.13,37.9,8.89z  \"><\/path>\t<path class=\"st0\" d=\"M27.65,42.15l-0.1,5.71l-5.99,8.83c-0.41,0.39-0.63,0.92-0.63,1.45c0,0.44,0.15,0.88,0.44,1.25  c0.64,0.81,1.82,0.98,2.67,0.39L32,50.54l1.5-5.86v-0.01\"><\/path>\t<path class=\"st0\" d=\"M28.41,25.75c3.19-0.55,6.55-0.95,9.82-1.11v-0.01C46.9,24.19,55.45,25.4,61.75,30  c-5.29,6.28-13.89,9.5-22.92,11.02c-2.93,0.51-5.92,0.82-8.85,1c-12.36,0.78-23.69-0.81-26.45-1.25c-0.35-0.05-0.58-0.39-0.53-0.74  L3.5,37l-1.2-2.85c-0.14-0.33,0.01-0.71,0.34-0.84c2.24-0.93,10.59-4.25,20.75-6.54\"><\/path>\t<line class=\"st0\" x1=\"36.44\" y1=\"24.75\" x2=\"51.45\" y2=\"37.41\"><\/line>\t<line class=\"st0\" x1=\"31.59\" y1=\"25.26\" x2=\"47.25\" y2=\"39\"><\/line><\/g><\/svg><\/div>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6ff1fbf2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6ff1fbf2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-47a00ed6 elementor-invisible\" data-id=\"47a00ed6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:360}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dccde42 elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"dccde42\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" height=\"512\" viewbox=\"0 0 512 512\" width=\"512\"><g id=\"XMLID_974_\"><g id=\"XMLID_1258_\"><g id=\"XMLID_509_\"><path id=\"XMLID_510_\" d=\"m109 396c-2.63 0-5.21 1.069-7.07 2.93-1.86 1.86-2.93 4.44-2.93 7.07s1.07 5.21 2.93 7.069c1.86 1.86 4.44 2.931 7.07 2.931s5.21-1.07 7.07-2.931c1.86-1.859 2.93-4.439 2.93-7.069s-1.07-5.21-2.93-7.07c-1.86-1.861-4.44-2.93-7.07-2.93z\"><\/path><path id=\"XMLID_635_\" d=\"m380 396c-2.63 0-5.21 1.069-7.07 2.93-1.86 1.86-2.93 4.44-2.93 7.07 0 2.64 1.07 5.21 2.93 7.069 1.86 1.86 4.44 2.931 7.07 2.931s5.21-1.07 7.07-2.931c1.86-1.859 2.93-4.439 2.93-7.069s-1.07-5.21-2.93-7.07c-1.86-1.861-4.44-2.93-7.07-2.93z\"><\/path><path id=\"XMLID_646_\" d=\"m440.373 140.066v-20.066h49.547c5.523 0 10-4.478 10-10 0-29.775-24.224-54-54-54h-102.874c-5.523 0-10 4.478-10 10s4.477 10 10 10h102.874c15.269 0 28.22 10.117 32.5 24h-360.999c4.28-13.883 17.23-24 32.499-24h103.126c5.523 0 10-4.478 10-10 0-5.523-4.477-10-10-10h-103.126c-29.776 0-54 24.225-54 54 0 5.522 4.477 10 10 10h49.547v20h-13.942c-34.438 0-64.11 23.386-72.158 56.87l-13.851 57.63c-31.92 8.478-55.516 37.614-55.516 72.167v79.333c0 5.522 4.477 10 10 10h50.006c4.646 22.795 24.847 40 48.994 40s44.348-17.205 48.994-40h173.012c4.646 22.795 24.847 40 48.994 40 24.146 0 44.348-17.205 48.994-40h73.006c5.523 0 10-4.478 10-10v-144-47.788c0-40.053-31.901-72.776-71.627-74.146zm-20-20.065v20h-20v-20zm-204.905 20v-20h164.905v20zm-40-20h20v20h-20zm-86.654 81.543c5.879-24.461 27.555-41.544 52.711-41.544h296.262c29.893 0 54.212 24.319 54.212 54.212v37.788h-24v-37c0-17.094-13.907-31-31-31h-55.917c-5.523 0-10 4.477-10 10v58h-24v-58c0-5.523-4.477-10-10-10h-82.895c-5.523 0-10 4.477-10 10v58h-24v-58c0-5.523-4.477-10-10-10h-67.837c-14.565 0-26.995 9.918-30.226 24.119l-9.988 43.881h-25.45zm359.186 50.457h-56.917v-48h45.917c6.065 0 11 4.935 11 11zm-120.917 0h-62.895v-48h62.895zm-126.894 0h-77.54l8.978-39.442c1.147-5.038 5.558-8.558 10.725-8.558h57.837zm-91.189 183.999c-16.542 0-30-13.458-30-30s13.458-30 30-30 30 13.458 30 30c0 16.543-13.458 30-30 30zm271 0c-16.542 0-30-13.458-30-30s13.458-30 30-30 30 13.458 30 30c0 16.543-13.458 30-30 30zm112-40h-63.006c-4.645-22.795-24.847-40-48.994-40s-44.348 17.205-48.994 40h-173.012c-4.645-22.795-24.847-40-48.994-40s-44.348 17.205-48.994 40h-40.006v-69.334c0-30.142 24.523-54.666 54.666-54.666h417.334z\"><\/path><path id=\"XMLID_658_\" d=\"m298.05 75.999c2.63 0 5.21-1.07 7.07-2.931 1.86-1.859 2.93-4.439 2.93-7.069s-1.07-5.21-2.93-7.07-4.44-2.93-7.07-2.93c-2.64 0-5.22 1.069-7.07 2.93-1.87 1.86-2.93 4.44-2.93 7.07s1.06 5.21 2.93 7.069c1.86 1.861 4.43 2.931 7.07 2.931z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLebendige Community Vibes\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tVon den spontanen Freuden der Segelt\u00f6rns, die Sie aufs Meer locken, bis hin zu den lachenden Grillabenden unter dem Sternenhimmel ist jeder Moment hier ein Fest des Lebens. Und wenn das Abenteuer ruft, antworten wir mit Ausfl\u00fcgen, die Sie \u00fcber die Grenzen von Tarifa hinaus in das Herz der windgepeitschten Landschaften f\u00fchren, die unsere Ecke der Welt einzigartig machen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-782cc7e elementor-invisible\" data-id=\"782cc7e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:720}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc00d03 elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"dc00d03\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" height=\"512\" viewbox=\"0 0 512.005 512.005\" width=\"512\"><g id=\"XMLID_967_\"><g id=\"XMLID_1025_\"><path id=\"XMLID_151_\" d=\"m256.002 272.56c-53.639 0-97.277-43.639-97.277-97.277s43.639-97.277 97.277-97.277c8.604 0 17.143 1.126 25.379 3.346 5.332 1.438 8.49 6.926 7.052 12.258-1.438 5.333-6.927 8.489-12.258 7.052-6.539-1.763-13.326-2.657-20.173-2.657-42.611 0-77.277 34.666-77.277 77.277s34.666 77.277 77.277 77.277 77.277-34.667 77.277-77.277c0-6.844-.893-13.629-2.655-20.167-1.437-5.332 1.721-10.821 7.054-12.258 5.334-1.436 10.821 1.721 12.258 7.054 2.219 8.234 3.344 16.77 3.344 25.371 0 53.639-43.639 97.278-97.278 97.278z\"><\/path><\/g><g id=\"XMLID_1054_\"><path id=\"XMLID_149_\" d=\"m421.285 185.282h-29.857c-5.523 0-10-4.477-10-10s4.477-10 10-10h29.857c5.523 0 10 4.477 10 10s-4.477 10-10 10z\"><\/path><\/g><g id=\"XMLID_1053_\"><path id=\"XMLID_148_\" d=\"m120.578 185.282h-29.858c-5.523 0-10-4.477-10-10s4.477-10 10-10h29.857c5.523 0 10 4.477 10 10 .001 5.523-4.476 10-9.999 10z\"><\/path><\/g><g id=\"XMLID_1052_\"><path id=\"XMLID_147_\" d=\"m256.002 350.564c-5.523 0-10-4.477-10-10v-29.857c0-5.523 4.477-10 10-10s10 4.477 10 10v29.857c0 5.523-4.477 10-10 10z\"><\/path><\/g><g id=\"XMLID_1051_\"><path id=\"XMLID_146_\" d=\"m256.002 49.857c-5.523 0-10-4.477-10-10v-29.857c0-5.523 4.477-10 10-10s10 4.477 10 10v29.857c0 5.523-4.477 10-10 10z\"><\/path><\/g><g id=\"XMLID_1049_\"><path id=\"XMLID_145_\" d=\"m372.875 302.154c-2.559 0-5.119-.976-7.071-2.929l-21.112-21.112c-3.905-3.905-3.905-10.237 0-14.143 3.905-3.905 10.237-3.905 14.143 0l21.112 21.112c3.905 3.905 3.905 10.237 0 14.143-1.954 1.953-4.513 2.929-7.072 2.929z\"><\/path><\/g><g id=\"XMLID_1048_\"><path id=\"XMLID_144_\" d=\"m160.243 89.522c-2.559 0-5.119-.976-7.071-2.929l-21.112-21.112c-3.905-3.905-3.905-10.237 0-14.143 3.905-3.905 10.237-3.905 14.143 0l21.112 21.112c3.905 3.905 3.905 10.237 0 14.143-1.954 1.953-4.513 2.929-7.072 2.929z\"><\/path><\/g><g id=\"XMLID_1047_\"><path id=\"XMLID_143_\" d=\"m139.13 302.154c-2.559 0-5.119-.976-7.071-2.929-3.905-3.905-3.905-10.237 0-14.143l21.112-21.112c3.905-3.905 10.237-3.905 14.143 0 3.905 3.905 3.905 10.237 0 14.143l-21.112 21.112c-1.953 1.953-4.513 2.929-7.072 2.929z\"><\/path><\/g><g id=\"XMLID_1046_\"><path id=\"XMLID_142_\" d=\"m351.762 89.522c-2.559 0-5.119-.976-7.071-2.929-3.905-3.905-3.905-10.237 0-14.143l21.112-21.112c3.905-3.905 10.237-3.905 14.143 0 3.905 3.905 3.905 10.237 0 14.143l-21.112 21.112c-1.953 1.953-4.513 2.929-7.072 2.929z\"><\/path><\/g><g id=\"XMLID_1063_\"><path id=\"XMLID_141_\" d=\"m115.431 441.207c-15.288 0-30.576-5.819-42.214-17.457-7.498-7.499-17.468-11.628-28.072-11.628s-20.573 4.13-28.071 11.628c-3.905 3.905-10.237 3.906-14.142 0-3.905-3.905-3.906-10.237 0-14.142 11.276-11.276 26.268-17.486 42.214-17.486 15.947 0 30.938 6.21 42.214 17.486 15.479 15.479 40.665 15.478 56.143-.001 11.276-11.276 26.268-17.486 42.214-17.486s30.938 6.21 42.214 17.486c15.479 15.479 40.665 15.478 56.144-.001 11.275-11.275 26.267-17.486 42.213-17.486s30.939 6.21 42.214 17.486c15.479 15.48 40.665 15.479 56.144 0 11.275-11.275 26.267-17.486 42.214-17.486 15.946 0 30.938 6.21 42.214 17.486 3.905 3.905 3.905 10.237 0 14.142-3.904 3.905-10.236 3.906-14.142 0-7.498-7.498-17.467-11.628-28.071-11.628s-20.574 4.13-28.072 11.628c-23.277 23.277-61.151 23.277-84.428 0-7.498-7.499-17.468-11.628-28.072-11.628s-20.573 4.13-28.071 11.628c-23.278 23.277-61.152 23.276-84.428 0-7.499-7.499-17.468-11.628-28.072-11.628s-20.574 4.13-28.072 11.628c-11.64 11.64-26.927 17.459-42.215 17.459z\"><\/path><\/g><g id=\"XMLID_972_\"><path id=\"XMLID_140_\" d=\"m115.431 512.005c-15.946 0-30.938-6.21-42.214-17.485-7.498-7.499-17.468-11.628-28.072-11.628s-20.573 4.129-28.071 11.628c-3.905 3.905-10.237 3.905-14.143 0-3.905-3.905-3.905-10.237 0-14.143 23.278-23.276 61.151-23.276 84.428 0 7.498 7.499 17.468 11.628 28.072 11.628s20.573-4.129 28.071-11.627c23.277-23.277 61.151-23.277 84.428-.001 15.479 15.479 40.665 15.48 56.144.001 23.276-23.276 61.15-23.277 84.427-.001 15.479 15.479 40.665 15.48 56.144.001 11.275-11.276 26.267-17.485 42.213-17.486 15.947 0 30.939 6.21 42.214 17.485 3.905 3.905 3.905 10.237 0 14.143-3.905 3.905-10.237 3.905-14.143 0-15.479-15.48-40.665-15.479-56.143 0-23.277 23.276-61.151 23.277-84.428 0-7.498-7.499-17.468-11.628-28.072-11.628s-20.573 4.129-28.072 11.628c-23.276 23.276-61.151 23.277-84.428 0-7.499-7.499-17.468-11.628-28.072-11.628s-20.574 4.129-28.072 11.628c-11.273 11.274-26.265 17.485-42.211 17.485z\"><\/path><\/g><g id=\"XMLID_1316_\"><g id=\"XMLID_1315_\"><path id=\"XMLID_139_\" d=\"m317.702 123.583c-2.63 0-5.21-1.07-7.07-2.93s-2.93-4.44-2.93-7.07 1.07-5.21 2.93-7.07 4.44-2.93 7.07-2.93 5.21 1.07 7.07 2.93 2.93 4.44 2.93 7.07-1.07 5.21-2.93 7.07c-1.86 1.859-4.44 2.93-7.07 2.93z\"><\/path><\/g><\/g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tErholsame R\u00fcckzugsorte\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tFinden Sie Ihr pers\u00f6nliches Refugium in den gem\u00fctlichen R\u00e4umen unserer Zimmer und Apartments. Jeder Raum ist ein Zeugnis des ruhigen Geistes von Tarifa, entworfen, um Ihr bequemer R\u00fcckzugsort nach einem Tag voller Surfen und Aufregung zu sein. Steigen Sie auf unsere Dachterrassen mit Panoramablick und atmen Sie die Sch\u00f6nheit des Horizonts ein, wo das Azur des Himmels mit dem tiefen Blau des Meeres tanzt. Es ist mehr als nur ein Aufenthalt; es ist eine Umarmung der sanften Seite des K\u00fcstenlebens.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1eb9cfa6 elementor-invisible\" data-id=\"1eb9cfa6\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;zoomIn&quot;,&quot;animation_delay&quot;:1080}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a32981 elementor-view-default elementor-position-top elementor-mobile-position-top elementor-widget elementor-widget-icon-box\" data-id=\"7a32981\" data-element_type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"Capa_1\" height=\"512\" viewbox=\"0 0 512.02 512.02\" width=\"512\"><g id=\"XMLID_15_\"><g id=\"XMLID_489_\"><path id=\"XMLID_1514_\" d=\"m443.156 258.315c-5.282-1.607-10.871 1.371-12.479 6.655l-15.073 49.522c-15.286 50.222-56.838 87.292-108.439 96.742-5.433.995-9.029 6.206-8.034 11.638.883 4.824 5.09 8.2 9.824 8.2.598 0 1.204-.054 1.814-.166 8.906-1.631 17.623-4.015 26.064-7.105v78.22c0 5.523 4.478 10 10 10s10-4.477 10-10v-87.143c11.108-5.9 21.537-13.119 31.048-21.544 22.064-19.546 38.267-44.796 46.857-73.019l15.073-49.521c1.607-5.284-1.372-10.871-6.655-12.479z\"><\/path><path id=\"XMLID_1517_\" d=\"m469.625 65.996c-12.007-6.293-25.724-7.457-38.622-3.273-12.897 4.183-23.32 13.174-29.35 25.318l-51.02 102.773c-1.466 2.952-4.423 4.786-7.718 4.786-4.75 0-8.615-3.865-8.615-8.616v-89.202c0-22.747-18.506-41.252-41.253-41.252-12.483 0-23.681 5.582-31.252 14.371-7.571-8.79-18.769-14.371-31.252-14.371-12.484 0-23.682 5.582-31.253 14.371-7.571-8.79-18.769-14.371-31.252-14.371-22.746 0-41.252 18.505-41.252 41.252v5.72l-28.046-75.5c-4.081-10.991-12.242-19.639-22.977-24.352-10.736-4.713-22.627-4.866-33.48-.433-19.62 8.016-30.542 29.566-25.405 50.128l47.311 189.388v31.267c0 37.691 13.461 74.25 37.904 102.941 7.026 8.247 14.842 15.697 23.291 22.275v102.804c0 5.523 4.478 10 10 10s10-4.477 10-10v-89.527c16.122 9.027 33.817 15.248 52.318 18.225.538.086 1.073.128 1.601.128 4.823 0 9.07-3.498 9.861-8.413.877-5.453-2.831-10.585-8.284-11.462-67.615-10.881-116.692-68.487-116.692-136.973v-32.497c0-.817-.1-1.631-.298-2.423l-47.608-190.58c-2.743-10.979 3.089-22.486 13.564-26.766 5.797-2.368 12.146-2.286 17.877.232 5.732 2.516 10.09 7.134 12.27 13.002l46.794 125.971v19.453c0 22.747 18.506 41.252 41.252 41.252 9.793 0 18.795-3.436 25.878-9.159 6.875 13.238 20.708 22.308 36.627 22.308 18.478 0 34.157-12.212 39.391-28.989 6.598 4.48 14.555 7.101 23.113 7.101 10.033 0 19.237-3.604 26.396-9.579 5.176 7.414 13.765 12.277 23.472 12.277 10.942 0 20.764-6.089 25.631-15.891l51.021-102.774c3.616-7.285 9.869-12.679 17.605-15.188 7.738-2.509 15.965-1.812 23.168 1.963 12.746 6.68 18.956 21.521 14.767 35.287l-18.198 59.787c-1.608 5.284 1.371 10.871 6.654 12.479 5.283 1.61 10.871-1.371 12.478-6.654l18.198-59.788c6.986-22.95-3.367-47.69-24.615-58.826zm-301.587 135.645c-11.719 0-21.252-9.534-21.252-21.252v-82.607c0-11.718 9.533-21.252 21.252-21.252s21.252 9.534 21.252 21.252v82.607c0 11.719-9.533 21.252-21.252 21.252zm83.757-8.103c0 11.718-9.533 21.252-21.252 21.252s-21.253-9.534-21.253-21.252v-95.756c0-11.718 9.534-21.252 21.253-21.252s21.252 9.534 21.252 21.252zm41.252-.635c-11.719 0-21.252-9.534-21.252-21.252v-73.869c0-11.718 9.533-21.252 21.252-21.252s21.253 9.534 21.253 21.252v73.869c0 11.718-9.534 21.252-21.253 21.252z\"><\/path><path id=\"XMLID_1560_\" d=\"m348.209 249.022c0-5.523-4.477-10-10-10-59.211 0-107.383 48.171-107.383 107.382 0 5.523 4.478 10 10 10 5.523 0 10-4.477 10-10 0-48.183 39.2-87.382 87.383-87.382 5.523 0 10-4.477 10-10z\"><\/path><path id=\"XMLID_1561_\" d=\"m453.362 214.79c-2.64 0-5.21 1.07-7.079 2.93-1.86 1.86-2.921 4.44-2.921 7.07s1.061 5.21 2.921 7.07c1.869 1.86 4.439 2.93 7.079 2.93 2.631 0 5.2-1.07 7.07-2.93 1.86-1.86 2.93-4.44 2.93-7.07s-1.069-5.21-2.93-7.07c-1.87-1.86-4.439-2.93-7.07-2.93z\"><\/path><\/g><\/g><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tUnerm\u00fcdliche Unterst\u00fctzung\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tGanz gleich, ob Sie \u00fcber die besten Restaurants in der Umgebung nachdenken, Ratschl\u00e4ge zum Verleih von Surfbrettern suchen oder sich \u00fcber die Gezeiten informieren m\u00f6chten, unser sachkundiges Team hat immer eine Antwort parat. Wir sind hier, um jeden Aspekt Ihres Aufenthalts reibungslos zu gestalten, damit Sie sich auf das konzentrieren k\u00f6nnen, was wirklich wichtig ist - jede Welle zu genie\u00dfen, sowohl im Wasser als auch au\u00dferhalb.\nIn der Surfers Residence vereinen sich unser Spa\u00dfhaus, unsere komfortablen Aufenthalte und unser Engagement f\u00fcr Ihre Zufriedenheit zu einem unvergesslichen Urlaub.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c14447 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c14447\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0cb0128\" data-id=\"0cb0128\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-993933b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"993933b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a5ed3e6\" data-id=\"a5ed3e6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56a000d elementor-widget elementor-widget-heading\" data-id=\"56a000d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Entdecken Sie die Freude an Ihrem eigenen Zuhause<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e306802\" data-id=\"e306802\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73ccd98 elementor-widget elementor-widget-text-editor\" data-id=\"73ccd98\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><a href=\"https:\/\/www.surfers-residence.com\/de\/\">SurferResidenz<\/a><\/strong>\u00a0empf\u00e4ngt Besucher aus der ganzen Welt und ist das ganze Jahr \u00fcber ge\u00f6ffnet. Diese besondere Mischung aus Surfer- und Kiterresidenz mit einem\u00a0<strong>Andalusisch-maurisches Flair<\/strong>\u00a0f\u00fchlt sich jeder wie zu Hause. Unser\u00a0<strong>selbst geschaffene und originelle Einrichtungsgegenst\u00e4nde und Merkmale<\/strong>\u00a0geben ihm einen ganz besonderen Charakter.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f8c3b3 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"0f8c3b3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.surfers-residence.com\/de\/the-house\/rooms\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pr\u00fcfen Sie unsere Zimmer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-01f996f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"01f996f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b41ac77 elementor-invisible\" data-id=\"b41ac77\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:720}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe45e09 ekit-equal-height-enable elementor-widget elementor-widget-elementskit-image-box\" data-id=\"fe45e09\" data-element_type=\"widget\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-left hover_from_left hover-border-bottom\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-left\">\n\n                    <img decoding=\"async\" width=\"2240\" height=\"1493\" src=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Recepcion_1.jpg\" class=\"attachment-full size-full wp-image-568\" alt=\"\" srcset=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Recepcion_1.jpg 2240w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Recepcion_1-300x200.jpg 300w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Recepcion_1-1024x683.jpg 1024w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Recepcion_1-768x512.jpg 768w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Recepcion_1-1536x1024.jpg 1536w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Recepcion_1-2048x1365.jpg 2048w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Erdgeschoss\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Die Eingangsebene bietet eine Mischung aus Zweckm\u00e4\u00dfigkeit und <b>Shop<\/b>, <b>gem\u00fctliche Wohnungen<\/b>eine einladende <b>Terrasse<\/b>und <b>Getriebelagerung<\/b>.                    <\/div>\n                                    <\/div>\n\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6d7f044 elementor-invisible\" data-id=\"6d7f044\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:360}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-241ab76 ekit-equal-height-enable elementor-widget elementor-widget-elementskit-image-box\" data-id=\"241ab76\" data-element_type=\"widget\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-left hover_from_left hover-border-bottom\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-left\">\n\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Salon-comun--scaled.jpg\" class=\"attachment-full size-full wp-image-363\" alt=\"\" srcset=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Salon-comun--scaled.jpg 2560w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Salon-comun--300x200.jpg 300w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Salon-comun--1024x683.jpg 1024w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Salon-comun--768x512.jpg 768w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Salon-comun--1536x1024.jpg 1536w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Salon-comun--2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Erster Stock\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Komfortable Eigenschaften <b>Schlafr\u00e4ume <\/b>und eine <b>gemeinschaftlicher Lebensraum<\/b> mit einer <b>Terrasse<\/b> zur Entspannung und zum geselligen Beisammensein.                    <\/div>\n                                    <\/div>\n\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cd8ffb0 elementor-invisible\" data-id=\"cd8ffb0\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8af8d6c ekit-equal-height-enable elementor-widget elementor-widget-elementskit-image-box\" data-id=\"8af8d6c\" data-element_type=\"widget\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-left hover_from_left hover-border-bottom\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-left\">\n\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Terraza-2--scaled.jpg\" class=\"attachment-full size-full wp-image-361\" alt=\"\" srcset=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Terraza-2--scaled.jpg 2560w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Terraza-2--300x200.jpg 300w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Terraza-2--1024x683.jpg 1024w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Terraza-2--768x512.jpg 768w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Terraza-2--1536x1024.jpg 1536w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Terraza-2--2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Zweite Etage\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Veranstaltet eine kommunale <b>K\u00fcche<\/b> und bietet Zugang zu <b>Dachterrassen<\/b> f\u00fcr Versammlungen und zum Genie\u00dfen der Aussicht.                    <\/div>\n                                    <\/div>\n\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a39643c elementor-invisible\" data-id=\"a39643c\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-298d4e0 ekit-equal-height-enable elementor-widget elementor-widget-elementskit-image-box\" data-id=\"298d4e0\" data-element_type=\"widget\" data-widget_type=\"elementskit-image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n            <div class=\"elementskit-info-image-box ekit-image-box text-left hover_from_left hover-border-bottom\" >\n\n                \n                <div class=\"elementskit-box-header image-box-img-left\">\n\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/DSF6196-scaled.jpg\" class=\"attachment-full size-full wp-image-364\" alt=\"\" srcset=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/DSF6196-scaled.jpg 2560w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/DSF6196-300x200.jpg 300w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/DSF6196-1024x683.jpg 1024w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/DSF6196-768x512.jpg 768w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/DSF6196-1536x1024.jpg 1536w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/DSF6196-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\n                <\/div>\n                \n                <div class=\"elementskit-box-body ekit-image-box-body\">\n                    <div class=\"elementskit-box-content ekit-image-box-body-inner\">\n                                                <h3 class=\"elementskit-info-box-title\">\n\n                        Einrichtungen\n                        \n                    <\/h3>\n                                                            <div class=\"elementskit-box-style-content\">\n                        Zu den modernen Annehmlichkeiten geh\u00f6ren Klimaanlage, Fu\u00dfbodenheizung und kostenloses Wi-Fi, die Ihren Aufenthalt in dieser erstklassigen Strandlage noch angenehmer machen.                    <\/div>\n                                    <\/div>\n\n                            <\/div>\n            <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14f5e4c5 animated-fast elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"14f5e4c5\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;animation&quot;:&quot;slideInUp&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:548,&quot;url&quot;:&quot;https:\\\/\\\/www.surfers-residence.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/close-up-hydrofoil-surf-board-kite-equipment-on-wooden-pier-jetty-shore-watersport-spot-bright-sunny.jpg&quot;},{&quot;id&quot;:544,&quot;url&quot;:&quot;https:\\\/\\\/www.surfers-residence.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/person-surfing-and-flying-a-parachute-at-the-same-time-in-kitesurfing-bonaire-caribbean.jpg&quot;},{&quot;id&quot;:545,&quot;url&quot;:&quot;https:\\\/\\\/www.surfers-residence.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/kitesurfing-seen-from-the-dunes-at-sunset.jpg&quot;},{&quot;id&quot;:97,&quot;url&quot;:&quot;https:\\\/\\\/www.surfers-residence.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Surfers-Residence-Tarifa-Kitesurf_2-scaled.jpg&quot;},{&quot;id&quot;:108,&quot;url&quot;:&quot;https:\\\/\\\/www.surfers-residence.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Surfers-Residence-Tarifa-surf_1-scaled.jpg&quot;}],&quot;background_slideshow_slide_duration&quot;:4000,&quot;background_slideshow_transition_duration&quot;:1500,&quot;background_slideshow_ken_burns&quot;:&quot;yes&quot;,&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_ken_burns_zoom_direction&quot;:&quot;in&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7f0fa17c\" data-id=\"7f0fa17c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-425e5cd0\" data-id=\"425e5cd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44181978 elementor-widget elementor-widget-heading\" data-id=\"44181978\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Begeben Sie sich auf das ultimative Wind-Abenteuer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a2c3d9f elementor-widget elementor-widget-heading\" data-id=\"5a2c3d9f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Reiten Sie mit uns durch den Wind<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3958c5c9 elementor-widget elementor-widget-text-editor\" data-id=\"3958c5c9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In der Surfers Residence schl\u00e4gt unser Puls im Rhythmus des Windes, und unsere Stimmung steigt mit den Drachen, die \u00fcber den Himmel von Tarifa tanzen. Unsere Kite Camps und Kurse verk\u00f6rpern die Essenz von Freiheit und Nervenkitzel, die das Kitesurfen verspricht. Egal, ob Sie zum ersten Mal die Brise nutzen oder ob Sie ein erfahrener Fahrer sind, der neue Wege \u00fcber die Wellen sucht, unsere erfahrenen Lehrer f\u00fchren Sie mit Pr\u00e4zision und Sorgfalt.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58cc0ed7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58cc0ed7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-275fd74c\" data-id=\"275fd74c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d793626 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4d793626\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fachkundige Unterweisung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ma\u00dfgeschneiderte Erlebnisse<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-15889b0f\" data-id=\"15889b0f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-547b3405 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"547b3405\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Weltklasse-Standorte<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Unendliche Abenteuer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f7ddf96 elementor-widget elementor-widget-button\" data-id=\"6f7ddf96\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.surfers-residence.com\/de\/kitecamp\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr Infos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-08a5d89 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08a5d89\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d2e817b\" data-id=\"d2e817b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9cb7628 elementor-widget elementor-widget-heading\" data-id=\"9cb7628\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Beliebte Fragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27ad82d elementor-widget elementor-widget-heading\" data-id=\"27ad82d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00e4ufig gestellte Fragen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00bdeb7 elementor-widget elementor-widget-text-editor\" data-id=\"00bdeb7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Um Sie bei Ihrer Buchung zu unterst\u00fctzen oder um Ihnen eine<br \/>Hier finden Sie weitere Informationen zu unserer SurferResidenz in Tarifa, sowie eine Liste Ihrer Fragen, die wir f\u00fcr Sie beantwortet haben.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3668ca2 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3668ca2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:360}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2240\" height=\"1493\" src=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Levante-Tarifa-Surfers-Residence-6.jpg\" class=\"attachment-full size-full wp-image-408\" alt=\"\" srcset=\"https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Levante-Tarifa-Surfers-Residence-6.jpg 2240w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Levante-Tarifa-Surfers-Residence-6-300x200.jpg 300w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Levante-Tarifa-Surfers-Residence-6-1024x683.jpg 1024w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Levante-Tarifa-Surfers-Residence-6-768x512.jpg 768w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Levante-Tarifa-Surfers-Residence-6-1536x1024.jpg 1536w, https:\/\/www.surfers-residence.com\/wp-content\/uploads\/2024\/03\/Levante-Tarifa-Surfers-Residence-6-2048x1365.jpg 2048w\" sizes=\"(max-width: 2240px) 100vw, 2240px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8b6b097\" data-id=\"8b6b097\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2719813 elementor-invisible elementor-widget elementor-widget-elementskit-accordion\" data-id=\"2719813\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInRight&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a5729cac84a9\">\n\n            \n                <div class=\"elementskit-card active\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-2719813\">\n                        <a href=\"#collapse-f8725c56a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f8725c56a5729cac84a9\" aria-expanded=\"true\" aria-controls=\"Collapse-f8725c56a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Wie kann ich ein Zimmer buchen?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f8725c56a5729cac84a9\" class=\"show collapse\" aria-labelledby=\"primaryHeading-0-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Sie k\u00f6nnen direkt \u00fcber die Schaltfl\u00e4che JETZT BUCHEN oben auf der Seite buchen. Sie k\u00f6nnen Ihr Zimmer auch auf unserer Seite ZIMMER buchen. Oder nutzen Sie unser Kontaktformular auf der Seite KONTAKT.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-2719813\">\n                        <a href=\"#collapse-fbf777b6a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-fbf777b6a5729cac84a9\" aria-expanded=\"false\" aria-controls=\"Collapse-fbf777b6a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Wo befindet sich der n\u00e4chstgelegene Flughafen?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-fbf777b6a5729cac84a9\" class=\"collapse\" aria-labelledby=\"primaryHeading-1-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Gibraltar 46 km, Jerez de la Frontera 127 km, M\u00e1laga 153 km, Sevilla 217 km. Die Anreise mit dem Flugzeug von Deutschland und Nordeuropa nach Andalusien ist sehr einfach und preiswert. Sie k\u00f6nnen 4 Flugh\u00e4fen anfliegen und die Flugzeit betr\u00e4gt ca. 2-3 Stunden. Von Deutschland aus fliegen Sie am besten nach Malaga oder Jerez, diese beiden Flugh\u00e4fen werden von Ryanair, Easyjet, Airberlin, Condor, German Wings und vielen mehr angeflogen. Der n\u00e4chstgelegene Flughafen \"Gibraltar\" ist perfekt f\u00fcr unsere britischen Freunde. Weiter entfernt befindet sich der Flughafen von Sevilla.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-2719813\">\n                        <a href=\"#collapse-cd936796a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-cd936796a5729cac84a9\" aria-expanded=\"false\" aria-controls=\"Collapse-cd936796a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Wo ist der n\u00e4chstgelegene Supermarkt?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-cd936796a5729cac84a9\" class=\"collapse\" aria-labelledby=\"primaryHeading-2-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Treten Sie einfach aus der T\u00fcr der SurfersResidence und \u00fcberqueren Sie die Gasse. Der kleine Tante-Emma-Laden bietet eine Vielzahl von Dingen (Brot, Obst, Getr\u00e4nke, alles, was Sie brauchen) und seine \u00d6ffnungszeiten sind 8 - 14 Uhr und 17 - 21 Uhr. Es gibt auch einen 24-Stunden-Supermarkt, der ganz in unserer N\u00e4he ist! Gehen Sie einfach zur Puerta Jerez, gehen Sie hindurch und dann 10 m nach links. Direkt neben dem Taxistand. Es dauert weniger als 3 Minuten, um dorthin zu gelangen!<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-2719813\">\n                        <a href=\"#collapse-e646cab6a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-e646cab6a5729cac84a9\" aria-expanded=\"false\" aria-controls=\"Collapse-e646cab6a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Wo ist der n\u00e4chstgelegene Geldautomat?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-e646cab6a5729cac84a9\" class=\"collapse\" aria-labelledby=\"primaryHeading-3-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>In Tarifa finden Sie zahlreiche Geldautomaten. Der n\u00e4chstgelegene befindet sich in der Calle Nuestra Se\u00f1ora de la Luz.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-2719813\">\n                        <a href=\"#collapse-8eb25796a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-8eb25796a5729cac84a9\" aria-expanded=\"false\" aria-controls=\"Collapse-8eb25796a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Wo kann ich einen Internetzugang bekommen?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-8eb25796a5729cac84a9\" class=\"collapse\" aria-labelledby=\"primaryHeading-4-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Internetzugang ist in unserem Haus verf\u00fcgbar, fragen Sie einfach nach dem Passwort bei Ihrer Ankunft!<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-2719813\">\n                        <a href=\"#collapse-e82d1d56a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-e82d1d56a5729cac84a9\" aria-expanded=\"false\" aria-controls=\"Collapse-e82d1d56a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Wo kann ich eine Tagestour, Spanischunterricht oder Walbeobachtung buchen?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-e82d1d56a5729cac84a9\" class=\"collapse\" aria-labelledby=\"primaryHeading-5-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Fragen Sie uns einfach und wir geben Ihnen alle Informationen, die Sie f\u00fcr die von Ihnen gew\u00fcnschte Tour oder Reise ben\u00f6tigen.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-2719813\">\n                        <a href=\"#collapse-6ceb8f16a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-6ceb8f16a5729cac84a9\" aria-expanded=\"false\" aria-controls=\"Collapse-6ceb8f16a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Muss ich Bettw\u00e4sche und Handt\u00fccher mitbringen?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-6ceb8f16a5729cac84a9\" class=\"collapse\" aria-labelledby=\"primaryHeading-6-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Wir stellen Ihnen die Bettw\u00e4sche zur Verf\u00fcgung, aber bitte bringen Sie Ihre eigenen Handt\u00fccher mit.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-7-2719813\">\n                        <a href=\"#collapse-0a57eb96a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0a57eb96a5729cac84a9\" aria-expanded=\"false\" aria-controls=\"Collapse-0a57eb96a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Wo kann ich mein Auto parken?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0a57eb96a5729cac84a9\" class=\"collapse\" aria-labelledby=\"primaryHeading-7-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Das Parken in Tarifa ist ein bisschen schwierig. Parken Sie NICHT auf den gelben Linien, Ihr Auto wird abgeschleppt! Die BLAUEN Linien sind geb\u00fchrenpflichtige Zonen. Zeigen Sie also unbedingt Ihren Parkschein vor, sonst werden Sie bestraft.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-8-2719813\">\n                        <a href=\"#collapse-9aec5d66a5729cac84a9\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9aec5d66a5729cac84a9\" aria-expanded=\"false\" aria-controls=\"Collapse-9aec5d66a5729cac84a9\">\n                            \n                            <span class=\"ekit-accordion-title\">Ist das Rauchen in der Surfers Residence erlaubt?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_right-up\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n\t\t\t\t\t\t\t\t\t\t<i class=\"arrow_left-down\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9aec5d66a5729cac84a9\" class=\"collapse\" aria-labelledby=\"primaryHeading-8-2719813\" data-parent=\"#accordion-6a5729cac84a9\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <p>Rauchen ist im Haus verboten - nur auf der Dachterrasse oder au\u00dferhalb des Geb\u00e4udes.<\/p>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                                        <\/div>\n    <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>\u00dcber uns Den Wind fangen: Der Pionier hinter unserer Leidenschaft Der Geist von Surfers Residence: Juliaans#8217; Verm\u00e4chtnis Ein Athlet mit brennender Leidenschaft f\u00fcr Kitesurfen. Juliaan ist ein IKO &amp; VDWS Kite-Instruktor und ein erfolgreicher Gr\u00fcnder. Er lernte vor 20 Jahren auf Fuerteventura Kitesurfen und ist seitdem vom Kite-Virus infiziert. [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-230","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.surfers-residence.com\/de\/wp-json\/wp\/v2\/pages\/230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.surfers-residence.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.surfers-residence.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.surfers-residence.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.surfers-residence.com\/de\/wp-json\/wp\/v2\/comments?post=230"}],"version-history":[{"count":0,"href":"https:\/\/www.surfers-residence.com\/de\/wp-json\/wp\/v2\/pages\/230\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.surfers-residence.com\/de\/wp-json\/wp\/v2\/media?parent=230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}